{"id":29855,"date":"2025-12-09T21:32:19","date_gmt":"2025-12-09T20:32:19","guid":{"rendered":"https:\/\/lightflow.info\/?post_type=product&#038;p=29855"},"modified":"2026-01-25T17:53:47","modified_gmt":"2026-01-25T16:53:47","slug":"1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s","status":"publish","type":"product","link":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/","title":{"rendered":"1.194 \u00dcbertragungen aus der 5. Bibliothek des Lichts &#8211; MP3s"},"content":{"rendered":"<p><strong>Aufruf an die Menschheit zu erwachen<\/strong><\/p>\n<p>In diesem Kurs lernst du die neuesten Informationen \u00fcber die 5. Bibliothek des Lichts kennen. Sie ist ein riesiger Sender des g\u00f6ttlichen Friedens und der Einseins, den die neuen Erdengel bewohnen werden. Die Erdengel sind hier, um den Weg f\u00fcr die &#8222;Seele der Menschheit&#8220; vorzubereiten, indem sie Botschaften \u00fcber die spirituelle Evolution an uns alle senden und uns helfen, \u00fcber die Illusionen hinauszusehen, die uns an dichtere Erfahrungen binden. Du wirst einen Lichttempel besuchen und \u00dcbertragungen nur f\u00fcr dich aus der 5. Bibliothek des Lichts empfangen. Diese heilenden \u00dcbertragungen haben den Zweck, dein Licht zu st\u00e4rken und dein Zentrum des g\u00f6ttlichen Friedens weiterzuentwickeln. In der zweiten Meditation unterst\u00fctzt du die 5. Bibliothek des Lichts, wenn sie die Menschheit dazu aufruft, zu dem zu erwachen, wer, was und warum sie ist.<\/p>\n<p><strong>Webinar-Aufnahmen:<\/strong> Dieses Produkt enth\u00e4lt 2 gechannelte Meditationen und erkl\u00e4rende Gespr\u00e4che, aufgezeichnet auf Kreta im Oktober 2022.<\/p>\n<p><strong>Wie erhalte ich mein gekauftes Produkt?<\/strong> Du erh\u00e4ltst das Produkt (MP3-Dateien) mit WeTransfer innerhalb von 2 Werktagen nach Abschluss der Bestellung.<\/p>\n<p><strong>Sprache:<\/strong> Cecilia channelt in Englisch und wird von Alexander konsekutiv auf Deutsch \u00fcbersetzt.<\/p>\n<p><strong>Mehrere Teilnehmende?<\/strong> Der Preis gilt pro Teilnehmer. Sollten also mehrere am Webinar teilnehmen, addiere bitte die entsprechende Anzahl im Warenkorb.<\/p>\n<p><strong>Fragen &amp; Ausk\u00fcnfte:<\/strong> Unser Organisator Roland Jundt hilft dir gerne weiter: <a href=\"mailto:roland@Lightflow.info\">roland@Lightflow.info<\/a>, +41 (0)79 32 064 32<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Kurs lernst du die neuesten Informationen \u00fcber die 5. Bibliothek des Lichts kennen. Sie ist ein riesiger Sender des g\u00f6ttlichen Friedens und der Einseins, den die neuen Erdengel bewohnen werden. Die Erdengel sind hier, um den Weg f\u00fcr die &#8222;Seele der Menschheit&#8220; vorzubereiten, indem sie Botschaften \u00fcber die spirituelle Evolution an uns alle senden und uns helfen, \u00fcber die Illusionen hinauszusehen, die uns an dichtere Erfahrungen binden.<\/p>\n","protected":false},"featured_media":36179,"template":"","meta":{"_acf_changed":false,"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0"},"product_brand":[],"product_cat":[223],"product_tag":[],"class_list":["post-29855","product","type-product","status-publish","has-post-thumbnail","product_cat-event-aufzeichnungen","entry","has-media","first","instock","shipping-taxable","purchasable","product-type-simple","col","span_1_of_3","owp-content-center","item-entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-section","has-no-thumbnails","circle-sale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1.194 \u00dcbertragungen aus der 5. Bibliothek des Lichts - MP3s &#8902; Lightflow Academy by Cecilia Sifontes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1.194 \u00dcbertragungen aus der 5. Bibliothek des Lichts - MP3s &#8902; Lightflow Academy by Cecilia Sifontes\" \/>\n<meta property=\"og:description\" content=\"In diesem Kurs lernst du die neuesten Informationen \u00fcber die 5. Bibliothek des Lichts kennen. Sie ist ein riesiger Sender des g\u00f6ttlichen Friedens und der Einseins, den die neuen Erdengel bewohnen werden. Die Erdengel sind hier, um den Weg f\u00fcr die &quot;Seele der Menschheit&quot; vorzubereiten, indem sie Botschaften \u00fcber die spirituelle Evolution an uns alle senden und uns helfen, \u00fcber die Illusionen hinauszusehen, die uns an dichtere Erfahrungen binden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/\" \/>\n<meta property=\"og:site_name\" content=\"Lightflow Academy by Cecilia Sifontes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-25T16:53:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lightflow.info\/wp-content\/uploads\/Uebertragungen-5-Lichtbibliothek-2022-10-MP3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/produkt\\\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\\\/\",\"url\":\"https:\\\/\\\/lightflow.info\\\/de\\\/produkt\\\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\\\/\",\"name\":\"1.194 \u00dcbertragungen aus der 5. Bibliothek des Lichts - MP3s &#8902; Lightflow Academy by Cecilia Sifontes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/produkt\\\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/produkt\\\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lightflow.info\\\/wp-content\\\/uploads\\\/Uebertragungen-5-Lichtbibliothek-2022-10-MP3.webp\",\"datePublished\":\"2025-12-09T20:32:19+00:00\",\"dateModified\":\"2026-01-25T16:53:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/produkt\\\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lightflow.info\\\/de\\\/produkt\\\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/produkt\\\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lightflow.info\\\/wp-content\\\/uploads\\\/Uebertragungen-5-Lichtbibliothek-2022-10-MP3.webp\",\"contentUrl\":\"https:\\\/\\\/lightflow.info\\\/wp-content\\\/uploads\\\/Uebertragungen-5-Lichtbibliothek-2022-10-MP3.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/produkt\\\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lightflow.info\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/lightflow.info\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Events\",\"item\":\"https:\\\/\\\/lightflow.info\\\/de\\\/kategorie\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Event-Aufzeichnungen\",\"item\":\"https:\\\/\\\/lightflow.info\\\/de\\\/kategorie\\\/events\\\/event-aufzeichnungen\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"1.194 \u00dcbertragungen aus der 5. Bibliothek des Lichts &#8211; MP3s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/lightflow.info\\\/de\\\/\",\"name\":\"Lightflow Academy by Cecilia Sifontes\",\"description\":\"Awakening Lightworkers and Masters\",\"alternateName\":\"Lightflow\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lightflow.info\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1.194 \u00dcbertragungen aus der 5. Bibliothek des Lichts - MP3s &#8902; Lightflow Academy by Cecilia Sifontes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/","og_locale":"de_DE","og_type":"article","og_title":"1.194 \u00dcbertragungen aus der 5. Bibliothek des Lichts - MP3s &#8902; Lightflow Academy by Cecilia Sifontes","og_description":"In diesem Kurs lernst du die neuesten Informationen \u00fcber die 5. Bibliothek des Lichts kennen. Sie ist ein riesiger Sender des g\u00f6ttlichen Friedens und der Einseins, den die neuen Erdengel bewohnen werden. Die Erdengel sind hier, um den Weg f\u00fcr die \"Seele der Menschheit\" vorzubereiten, indem sie Botschaften \u00fcber die spirituelle Evolution an uns alle senden und uns helfen, \u00fcber die Illusionen hinauszusehen, die uns an dichtere Erfahrungen binden.","og_url":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/","og_site_name":"Lightflow Academy by Cecilia Sifontes","article_modified_time":"2026-01-25T16:53:47+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/lightflow.info\/wp-content\/uploads\/Uebertragungen-5-Lichtbibliothek-2022-10-MP3.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/","url":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/","name":"1.194 \u00dcbertragungen aus der 5. Bibliothek des Lichts - MP3s &#8902; Lightflow Academy by Cecilia Sifontes","isPartOf":{"@id":"https:\/\/lightflow.info\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/#primaryimage"},"image":{"@id":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/#primaryimage"},"thumbnailUrl":"https:\/\/lightflow.info\/wp-content\/uploads\/Uebertragungen-5-Lichtbibliothek-2022-10-MP3.webp","datePublished":"2025-12-09T20:32:19+00:00","dateModified":"2026-01-25T16:53:47+00:00","breadcrumb":{"@id":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/#primaryimage","url":"https:\/\/lightflow.info\/wp-content\/uploads\/Uebertragungen-5-Lichtbibliothek-2022-10-MP3.webp","contentUrl":"https:\/\/lightflow.info\/wp-content\/uploads\/Uebertragungen-5-Lichtbibliothek-2022-10-MP3.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/lightflow.info\/de\/produkt\/1-194-uebertragungen-aus-der-5-bibliothek-des-lichts-mp3s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lightflow.info\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lightflow.info\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Events","item":"https:\/\/lightflow.info\/de\/kategorie\/events\/"},{"@type":"ListItem","position":4,"name":"Event-Aufzeichnungen","item":"https:\/\/lightflow.info\/de\/kategorie\/events\/event-aufzeichnungen\/"},{"@type":"ListItem","position":5,"name":"1.194 \u00dcbertragungen aus der 5. Bibliothek des Lichts &#8211; MP3s"}]},{"@type":"WebSite","@id":"https:\/\/lightflow.info\/de\/#website","url":"https:\/\/lightflow.info\/de\/","name":"Lightflow Academy by Cecilia Sifontes","description":"Awakening Lightworkers and Masters","alternateName":"Lightflow","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lightflow.info\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product\/29855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product\/29855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/media\/36179"}],"wp:attachment":[{"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/media?parent=29855"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product_brand?post=29855"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product_cat?post=29855"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product_tag?post=29855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}