{"id":84,"count":2,"description":"Deine Seele ist ein freies, grenzenloses, ewiges und multidimensionales Wesen, das in einem ewigen Lichtnetz lebt. Du bringst diese Seelenqualit\u00e4ten in das Leben auf der Erde.","link":"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/die-12-schritte-des-goettlichen-plans\/","name":"Die 12 Schritte des g\u00f6ttlichen Plans","slug":"die-12-schritte-des-goettlichen-plans","taxonomy":"product_cat","parent":215,"meta":[],"menu_order":13,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die 12 Schritte des g\u00f6ttlichen Plans &#8902; Lightflow Academy by Cecilia Sifontes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/die-12-schritte-des-goettlichen-plans\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die 12 Schritte des g\u00f6ttlichen Plans &#8902; Lightflow Academy by Cecilia Sifontes\" \/>\n<meta property=\"og:description\" content=\"Deine Seele ist ein freies, grenzenloses, ewiges und multidimensionales Wesen, das in einem ewigen Lichtnetz lebt. Du bringst diese Seelenqualit\u00e4ten in das Leben auf der Erde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/die-12-schritte-des-goettlichen-plans\/\" \/>\n<meta property=\"og:site_name\" content=\"Lightflow Academy by Cecilia Sifontes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/kategorie\\\/engel-fuer-anfaenger\\\/die-12-schritte-des-goettlichen-plans\\\/\",\"url\":\"https:\\\/\\\/lightflow.info\\\/de\\\/kategorie\\\/engel-fuer-anfaenger\\\/die-12-schritte-des-goettlichen-plans\\\/\",\"name\":\"Die 12 Schritte des g\u00f6ttlichen Plans &#8902; Lightflow Academy by Cecilia Sifontes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/kategorie\\\/engel-fuer-anfaenger\\\/die-12-schritte-des-goettlichen-plans\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/kategorie\\\/engel-fuer-anfaenger\\\/die-12-schritte-des-goettlichen-plans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lightflow.info\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/lightflow.info\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Engel f\u00fcr Anf\u00e4nger\",\"item\":\"https:\\\/\\\/lightflow.info\\\/de\\\/kategorie\\\/engel-fuer-anfaenger\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Die 12 Schritte des g\u00f6ttlichen Plans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lightflow.info\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/lightflow.info\\\/de\\\/\",\"name\":\"Lightflow Academy by Cecilia Sifontes\",\"description\":\"Awakening Lightworkers and Masters\",\"alternateName\":\"Lightflow\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lightflow.info\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die 12 Schritte des g\u00f6ttlichen Plans &#8902; Lightflow Academy by Cecilia Sifontes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/die-12-schritte-des-goettlichen-plans\/","og_locale":"de_DE","og_type":"article","og_title":"Die 12 Schritte des g\u00f6ttlichen Plans &#8902; Lightflow Academy by Cecilia Sifontes","og_description":"Deine Seele ist ein freies, grenzenloses, ewiges und multidimensionales Wesen, das in einem ewigen Lichtnetz lebt. Du bringst diese Seelenqualit\u00e4ten in das Leben auf der Erde.","og_url":"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/die-12-schritte-des-goettlichen-plans\/","og_site_name":"Lightflow Academy by Cecilia Sifontes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/die-12-schritte-des-goettlichen-plans\/","url":"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/die-12-schritte-des-goettlichen-plans\/","name":"Die 12 Schritte des g\u00f6ttlichen Plans &#8902; Lightflow Academy by Cecilia Sifontes","isPartOf":{"@id":"https:\/\/lightflow.info\/de\/#website"},"breadcrumb":{"@id":"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/die-12-schritte-des-goettlichen-plans\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/die-12-schritte-des-goettlichen-plans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lightflow.info\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lightflow.info\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Engel f\u00fcr Anf\u00e4nger","item":"https:\/\/lightflow.info\/de\/kategorie\/engel-fuer-anfaenger\/"},{"@type":"ListItem","position":4,"name":"Die 12 Schritte des g\u00f6ttlichen Plans"}]},{"@type":"WebSite","@id":"https:\/\/lightflow.info\/de\/#website","url":"https:\/\/lightflow.info\/de\/","name":"Lightflow Academy by Cecilia Sifontes","description":"Awakening Lightworkers and Masters","alternateName":"Lightflow","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lightflow.info\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product_cat\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product_cat\/215"}],"wp:post_type":[{"href":"https:\/\/lightflow.info\/de\/wp-json\/wp\/v2\/product?product_cat=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}